{"id":7114,"date":"2021-06-08T17:48:44","date_gmt":"2021-06-08T21:48:44","guid":{"rendered":"https:\/\/interligne.co\/question-frequente\/what-is-homosexuality\/"},"modified":"2021-06-08T17:48:44","modified_gmt":"2021-06-08T21:48:44","slug":"what-is-homosexuality","status":"publish","type":"question-frequente","link":"https:\/\/interligne.co\/en\/question-frequente\/what-is-homosexuality\/","title":{"rendered":"What is homosexuality?"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","categorie-faq":[111],"class_list":["post-7114","question-frequente","type-question-frequente","status-publish","hentry","categorie-faq-sexual-orientation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>What is homosexuality? - Interligne<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interligne.co\/en\/question-frequente\/what-is-homosexuality\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What is homosexuality? - Interligne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interligne.co\/en\/question-frequente\/what-is-homosexuality\/\" \/>\n<meta property=\"og:site_name\" content=\"Interligne\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interligne.co\\\/en\\\/question-frequente\\\/what-is-homosexuality\\\/\",\"url\":\"https:\\\/\\\/interligne.co\\\/en\\\/question-frequente\\\/what-is-homosexuality\\\/\",\"name\":\"What is homosexuality? - Interligne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interligne.co\\\/en\\\/#website\"},\"datePublished\":\"2021-06-08T21:48:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interligne.co\\\/en\\\/question-frequente\\\/what-is-homosexuality\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interligne.co\\\/en\\\/question-frequente\\\/what-is-homosexuality\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interligne.co\\\/en\\\/question-frequente\\\/what-is-homosexuality\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/interligne.co\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What is homosexuality?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interligne.co\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/interligne.co\\\/en\\\/\",\"name\":\"Interligne\",\"description\":\"Votre espace pour LGBTQ+\",\"publisher\":{\"@id\":\"https:\\\/\\\/interligne.co\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interligne.co\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interligne.co\\\/en\\\/#organization\",\"name\":\"Interligne\",\"url\":\"https:\\\/\\\/interligne.co\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/interligne.co\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interligne.co\\\/wp-content\\\/uploads\\\/revslider\\\/accueil-v2-1\\\/interligne-color.png\",\"contentUrl\":\"https:\\\/\\\/interligne.co\\\/wp-content\\\/uploads\\\/revslider\\\/accueil-v2-1\\\/interligne-color.png\",\"width\":1000,\"height\":766,\"caption\":\"Interligne\"},\"image\":{\"@id\":\"https:\\\/\\\/interligne.co\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What is homosexuality? - Interligne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interligne.co\/en\/question-frequente\/what-is-homosexuality\/","og_locale":"en_US","og_type":"article","og_title":"What is homosexuality? - Interligne","og_url":"https:\/\/interligne.co\/en\/question-frequente\/what-is-homosexuality\/","og_site_name":"Interligne","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interligne.co\/en\/question-frequente\/what-is-homosexuality\/","url":"https:\/\/interligne.co\/en\/question-frequente\/what-is-homosexuality\/","name":"What is homosexuality? - Interligne","isPartOf":{"@id":"https:\/\/interligne.co\/en\/#website"},"datePublished":"2021-06-08T21:48:44+00:00","breadcrumb":{"@id":"https:\/\/interligne.co\/en\/question-frequente\/what-is-homosexuality\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interligne.co\/en\/question-frequente\/what-is-homosexuality\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/interligne.co\/en\/question-frequente\/what-is-homosexuality\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/interligne.co\/en\/"},{"@type":"ListItem","position":2,"name":"What is homosexuality?"}]},{"@type":"WebSite","@id":"https:\/\/interligne.co\/en\/#website","url":"https:\/\/interligne.co\/en\/","name":"Interligne","description":"Votre espace pour LGBTQ+","publisher":{"@id":"https:\/\/interligne.co\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interligne.co\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/interligne.co\/en\/#organization","name":"Interligne","url":"https:\/\/interligne.co\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/interligne.co\/en\/#\/schema\/logo\/image\/","url":"https:\/\/interligne.co\/wp-content\/uploads\/revslider\/accueil-v2-1\/interligne-color.png","contentUrl":"https:\/\/interligne.co\/wp-content\/uploads\/revslider\/accueil-v2-1\/interligne-color.png","width":1000,"height":766,"caption":"Interligne"},"image":{"@id":"https:\/\/interligne.co\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/interligne.co\/en\/wp-json\/wp\/v2\/question-frequente\/7114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interligne.co\/en\/wp-json\/wp\/v2\/question-frequente"}],"about":[{"href":"https:\/\/interligne.co\/en\/wp-json\/wp\/v2\/types\/question-frequente"}],"wp:attachment":[{"href":"https:\/\/interligne.co\/en\/wp-json\/wp\/v2\/media?parent=7114"}],"wp:term":[{"taxonomy":"categorie-faq","embeddable":true,"href":"https:\/\/interligne.co\/en\/wp-json\/wp\/v2\/categorie-faq?post=7114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}